{"id":24164,"date":"1996-07-20T18:37:08","date_gmt":"1996-07-20T16:37:08","guid":{"rendered":"https:\/\/www.pedro-gandia.com\/paraiso-terrenal-de-ricardo-llopesa\/"},"modified":"2017-09-22T20:34:21","modified_gmt":"2017-09-22T18:34:21","slug":"paraiso-terrenal-de-ricardo-llopesa","status":"publish","type":"post","link":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/","title":{"rendered":"PARA\u00cdSO TERRENAL DE RICARDO LLOPESA"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; background_animation=&#8221;none&#8221; css_animation=&#8221;&#8221;][vc_column][vc_column_text]<em>PARA\u00cdSO TERRENAL<\/em> DE RICARDO LLOPESA<\/p>\n<p>&nbsp;<\/p>\n<p>Pedro Gand\u00eda \/ <em>La Prensa Literaria<\/em>, Managua (Nicaragua) \u2015 <strong>20\/05\/1996<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Para\u00edso terrenal<\/em> (Instituto de Estudios Modernistas, Valencia, 1996), el \u00faltimo poemario publicado de Ricardo Llopesa (Masaya, Nicaragua, 1948), es un libro escrito en 1985, una alegor\u00eda en torno al tema del alcohol, treinta poemas como p\u00e1ginas de una vida. O lo que se sabe del vivir, desde la resaca.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Las sociedades de bebedores de anta\u00f1o, cuando la ortodoxia pesaba en exceso, eran asilo y refugio de las inteligencias libres. <em>En las tabernas se re\u00fanen a beber los desenga\u00f1ados<\/em>, se lee en \u201cRecinto de la ebriedad\u201d.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>La embriaguez es un acto de libertad por el que el ser humano se libra de la desilusi\u00f3n y la melancol\u00eda, haciendo de la existencia el momento perfecto.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>La sabidur\u00eda es la resaca de lo real, de vuelta al olvido. Los versos de <em>Para\u00edso terrenal<\/em> est\u00e1n escritos desde la resaca de la vida, en la hora en que Homero cantaba el mar, del color de vino.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>De vuelta del para\u00edso, las palabras se tornan enigm\u00e1ticas. Es lo enigm\u00e1tico de lo elemental, de la verdad m\u00e1s profunda. Llopesa desvela lo real en sus versos, y sus palabras fluyen como un manantial de monta\u00f1a.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Para\u00edso terrenal<\/em> revela la sabidur\u00eda de la existencia, del ser ante la muerte. Aqu\u00ed se escucha la verdad completamente humana del maestro, <em>le coeur mis \u00e0 nu<\/em>, dirigi\u00e9ndose al hip\u00f3crita lector, su semejante, su hermano. Y hay, al final del libro, un salud a Baudelaire, al poeta de <em>Los para\u00edsos artificiales<\/em>, del vino y del hach\u00eds, para quien &lt;&lt;<em>la vraie realit\u00e9 n\u2019est que dans les r\u00eaves<\/em>&gt;&gt;.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Para Llopesa, es el alcohol lo que conduce al sue\u00f1o. En \u201cHerencia\u201d, el poema con que se abre el libro, se nos dice que <em>somos hijos de la diosa ebriedad \/y el dios Vino<\/em>. El poeta lo afirma desde su malditismo, del que nos hace a todos part\u00edcipes <em>tendidos sobre la mullida alfombra del vicio<\/em>. En \u201cEl encanto de la nodriza\u201d, la m\u00edtica progenitora convierte la cebada en cerveza para <em>alimentar de sue\u00f1o la libertad del hombre<\/em>, una libertad de or\u00edgenes. El poeta vuelve a insistir, en \u201cAntesala del Para\u00edso\u201d, en que es el vino, <em>el l\u00edquido transparente del sue\u00f1o<\/em>, lo que nos conecta con el origen: <em>cuando ellos beb\u00edan \/ so\u00f1aban con nuestros antepasados<\/em>. Y el hombre, por el alcohol, alcanza el <em>Coraz\u00f3n del cielo<\/em>.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>La tristeza, la amargura que procura el sentimiento de la vida como espacio fatal, quedan abolidas por el alcohol. <em>Es m\u00e1s bello ver pasar el mundo \/ con los ojos iluminados de la ebriedad<\/em>, son versos de \u201cEl \u00e1ngel ciego\u201d. Y, en \u201cConjunci\u00f3n de los cuerpos\u201d, se nos dice que el alcohol transforma la vida en para\u00edso terrenal, <em>en fest\u00edn dionis\u00edaco \/ en org\u00eda envidiada por el mismo Ptolomeo.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Es este un poemario de antesala, con la lucidez de quien siente la precariedad de la existencia y ans\u00eda el olvido absoluto, el <em>olvidar el olvido<\/em> de su verso. El hombre es hombre porque tiene el olvido. Se trata de la sabidur\u00eda de los or\u00edgenes.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Beber es so\u00f1ar, o volar, en Llopesa. El <em>aqua vitae<\/em> o \u201cesp\u00edritu de sabidur\u00eda\u201d del poema \u201cSimilitud del origen\u201d. Y el poeta, que sabe la magia, regresa a sus ancestros, con el alcohol, <em>in vino veritas<\/em>, como met\u00e1fora. Met\u00e1fora que nos desv\u00eda al para\u00edso terrenal, donde el hombre fue dios creador para engendrarse en el otro. Narciso recre\u00e1ndose en un lago de alcohol para olvidarse en el otro, para olvidar al otro.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>El sujeto poem\u00e1tico de <em>Para\u00edso terrenal<\/em> expresa de continuo ese <em>redde mihi laetitia<\/em> del olvido. Y es su lucha existencial lo que le lleva a agarrarse y desasirse de la vida como un adolescente indisciplinado, como el poeta.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>No falta en el libro la referencia sociopol\u00edtica. El poeta se representa prisionero en una <em>enorme prisi\u00f3n con guardias, \/ con esp\u00edas, con polic\u00edas, con detectives privados.<\/em> Es el estado policial de un fascismo nuevo, como maquillaje democr\u00e1tico, del poema \u201cMartes Trece\u201d.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Desde la met\u00e1fora, y contra la met\u00e1fora y la posibilidad de alegor\u00eda, el alcohol es la luz. El poeta que viene de una tierra m\u00e1gica con tres volcanes de oro, de un para\u00edso terrenal perdido, siempre extranjero aun dentro de s\u00ed mismo, nos muestra la verdad m\u00e1s simple cuando nada se recuerda. El alcohol como v\u00eda de conocimiento, conocimiento del no conocimiento, <em>olvidar el olvido<\/em>, la luz de la verdad.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>En el poema \u201cLa embriaguez\u201d es Rabelais quien habla: <em>la embriaguez es mirar las cosas con ojos de ni\u00f1o; \/ es advertir el futuro desde el recuerdo, \/ contemplando, al mismo tiempo el olvido.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>La embriaguez es un don que nos viene de los dioses: <em>Bebo antes que t\u00fa para darte ejemplo; te invito a beber<\/em>, es una cita de la tradici\u00f3n antigua griega para el poema neoparnasiano \u201cLos hijos del Olimpo\u201d, donde Zeus bebe el <em>delicioso vino joven<\/em> de Dionisos y cae ebrio <em>sobre el polvo vaporoso del sue\u00f1o<\/em>.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Para\u00edso terrenal<\/em> est\u00e1 en la tradici\u00f3n del <em>carpe diem<\/em>, en la l\u00ednea de la filosof\u00eda de los sentidos\u00a0 de Omar Kheyyam, aquellos versos de <em>goza de la bebida \/ porque el Destino te llevar\u00e1 a la Nada.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Hay una exhortaci\u00f3n martilleando a la bebida, a alcanzar el para\u00edso. No es otro el \u00fanico consejo del libro de quien es fiel al alcohol hasta la muerte. En el poema \u201cConsejo a un adolescente\u201d, el poeta exhorta al que estrena la vida: <em>Date prisa, muchacho, \/ apres\u00farate a beber el vino de <\/em>Ispah\u00e1n<em>, \/ el vino espiritoso de <\/em>Marsala<em>, el napolitano <\/em>Lacryma christi<em> \/ que la muerte s\u00f3lo se lleva contigo \/ el delirio de lo vivido.<\/em> Es el vino verdadero y perfumado, y no el vivo ficticio, el que ha de gustarse.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Se cuenta, como an\u00e9cdota que ilustra la incultura de ciertos poderes, que al libro se le neg\u00f3 el premio \u201cVicente Gaos\u201d del Ayuntamiento de Valencia por estimar que incitaba a la bebida a los j\u00f3venes.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>B\u00e9quer ten\u00eda alegre la tristeza y triste el vino. Llopesa, con el alcohol, se libera de la tristeza. La borrachera es el lugar del Gaudium. <em>\u00a1He bebido tanto! \/ Quiz\u00e1 por eso sienta libre mi esp\u00edritu<\/em>, nos dice en \u201cEvocaci\u00f3n de la tristeza\u201d.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>El poemario est\u00e1 dedicado <em>a los poetas que habitaron el Para\u00edso terrenal de la embriaguez<\/em>. Y se cierra con un \u201cBrindis\u201d, una larga lista de <em>poetas, maestros, genios, beodos divinos, \/ hijos del Olimpo y hermanos de los dioses.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Ricardo Llopesa ha robado <em>el divino secreto de la embriaguez<\/em> para desvelarlo en sus versos, desde la resaca, arropado por una mitolog\u00eda de mestizaje, mitolog\u00eda precolombina (Tzacol, Bitol, Qaholara) y griega (Zeus, Dionisos), con la Hidra, Agamen\u00f3n, Dante y el poderoso Thor entremezclados, <em>en Managua, en San Jos\u00e9, \/ en Par\u00eds, en Tegucigalpa, en Madrid.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>A la manera del Johnny Carter de Cort\u00e1zar con la m\u00fasica, el poeta dilata el instante con el alcohol para gozar la eternidad de los sentidos, borrado todo l\u00edmite. Porque el instante es eterno y verdadero en su caducidad. &lt;&lt;El nombre de la estrella es Ajenjo&gt;&gt;, lo dice Charlie Parker, o &lt;&lt;Esto lo estoy tocando ma\u00f1ana&gt;&gt;.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>La vida es demasiado breve. Lo dice Llopesa con el t\u00edtulo de su primer poemario, <em>La vida breve<\/em> (1994); un barrido de c\u00e1mara ante el paisaje de lo vivido, recuerdos de vida.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Este es el poemario de un maldito, id\u00f3latra del placer del olvido. Las prostitutas son las<em> diosas del amor<\/em>, las <em>diosas del vicio<\/em>, las <em>diosas del placer divino<\/em> en \u201cLos burdeles de Masaya\u201d. Frente a una sociedad cada vez m\u00e1s <em>light<\/em>, el poeta reivindica el placer sensorial desde el lado salvaje de la existencia. Porque el tiempo, dilatado por la voluptuosidad, sea eternamente presente. O, aniquilado, no sea.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Pero Llopesa es, ante todo, un maldito porque hace de la belleza la corrupci\u00f3n de la forma, se entrega a la autodestrucci\u00f3n, por un acto de amor a los or\u00edgenes, para alcanzar el no-ser. Y lo dice con una lucidez excesiva: <em>la vida si breve es m\u00e1s bella \/ si es emblema de corrupci\u00f3n de la materia.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em>Los versos de <em>Para\u00edso terrenal<\/em> son los de un inspirado: <em>el chorro de la luz dicta \/ las l\u00edneas de la escritura.<\/em> Son los versos de quien ha gustado la eternidad del instante. Lo dice en el poema \u201cEternidad\u201d: <em>Todo tiempo bueno \/ exige un buen trago de guaro \/ donde la eternidad se edifique.<\/em> La eternidad como la nada, el para\u00edso terrenal.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 T\u00fa est\u00e1s a mitad del camino, sigue, bebe<\/em>. Es la l\u00ednea de salida de Dante en la<em> Comedia<\/em>. &lt;&lt;<em>Dans le texte, mais non dans l\u2019oeuvre<\/em>&gt;&gt;, dir\u00eda Roland Barthes. En Llopesa, s\u00ed; en la obra tambi\u00e9n, en la vida. El poeta se enfrenta aqu\u00ed, sin miedo, a la verdad del origen.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Para\u00edso terrenal (Instituto de Estudios Modernistas, Valencia, 1996), el \u00faltimo poemario publicado de Ricardo Llopesa (Masaya, Nicaragua, 1948), es un libro escrito en 1985, una alegor\u00eda en torno al tema del alcohol, treinta poemas como p\u00e1ginas de una vida. O lo que se sabe del vivir, desde la resaca. Las sociedades de bebedores de anta\u00f1o, cuando la ortodoxia pesaba en exceso, eran asilo y refugio de las inteligencias libres. En las tabernas se re\u00fanen a beber los desenga\u00f1ados, se lee en \u201cRecinto de la ebriedad\u201d. La embriaguez es un acto de libertad por el que el ser humano se libra de la desilusi\u00f3n y la melancol\u00eda, haciendo de la existencia el momento perfecto. La sabidur\u00eda es la resaca de lo real, de vuelta al olvido. Los versos de Para\u00edso terrenal est\u00e1n escritos desde la resaca de la vida, en la hora en que Homero cantaba el mar, del color de vino.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107,108],"tags":[],"class_list":["post-24164","post","type-post","status-publish","format-standard","hentry","category-literature","category-articles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PARA\u00cdSO TERRENAL DE RICARDO LLOPESA - Pedro Gand\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PARA\u00cdSO TERRENAL DE RICARDO LLOPESA - Pedro Gand\u00eda\" \/>\n<meta property=\"og:description\" content=\"Para\u00edso terrenal (Instituto de Estudios Modernistas, Valencia, 1996), el \u00faltimo poemario publicado de Ricardo Llopesa (Masaya, Nicaragua, 1948), es un libro escrito en 1985, una alegor\u00eda en torno al tema del alcohol, treinta poemas como p\u00e1ginas de una vida. O lo que se sabe del vivir, desde la resaca. Las sociedades de bebedores de anta\u00f1o, cuando la ortodoxia pesaba en exceso, eran asilo y refugio de las inteligencias libres. En las tabernas se re\u00fanen a beber los desenga\u00f1ados, se lee en \u201cRecinto de la ebriedad\u201d. La embriaguez es un acto de libertad por el que el ser humano se libra de la desilusi\u00f3n y la melancol\u00eda, haciendo de la existencia el momento perfecto. La sabidur\u00eda es la resaca de lo real, de vuelta al olvido. Los versos de Para\u00edso terrenal est\u00e1n escritos desde la resaca de la vida, en la hora en que Homero cantaba el mar, del color de vino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedro Gand\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"1996-07-20T16:37:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-22T18:34:21+00:00\" \/>\n<meta name=\"author\" content=\"Pedro Gand\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pedrogandia\" \/>\n<meta name=\"twitter:site\" content=\"@pedrogandia\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Gand\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PARA\u00cdSO TERRENAL DE RICARDO LLOPESA - Pedro Gand\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/","og_locale":"en_US","og_type":"article","og_title":"PARA\u00cdSO TERRENAL DE RICARDO LLOPESA - Pedro Gand\u00eda","og_description":"Para\u00edso terrenal (Instituto de Estudios Modernistas, Valencia, 1996), el \u00faltimo poemario publicado de Ricardo Llopesa (Masaya, Nicaragua, 1948), es un libro escrito en 1985, una alegor\u00eda en torno al tema del alcohol, treinta poemas como p\u00e1ginas de una vida. O lo que se sabe del vivir, desde la resaca. Las sociedades de bebedores de anta\u00f1o, cuando la ortodoxia pesaba en exceso, eran asilo y refugio de las inteligencias libres. En las tabernas se re\u00fanen a beber los desenga\u00f1ados, se lee en \u201cRecinto de la ebriedad\u201d. La embriaguez es un acto de libertad por el que el ser humano se libra de la desilusi\u00f3n y la melancol\u00eda, haciendo de la existencia el momento perfecto. La sabidur\u00eda es la resaca de lo real, de vuelta al olvido. Los versos de Para\u00edso terrenal est\u00e1n escritos desde la resaca de la vida, en la hora en que Homero cantaba el mar, del color de vino.","og_url":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/","og_site_name":"Pedro Gand\u00eda","article_published_time":"1996-07-20T16:37:08+00:00","article_modified_time":"2017-09-22T18:34:21+00:00","author":"Pedro Gand\u00eda","twitter_card":"summary_large_image","twitter_creator":"@pedrogandia","twitter_site":"@pedrogandia","twitter_misc":{"Written by":"Pedro Gand\u00eda","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/#article","isPartOf":{"@id":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/"},"author":{"name":"Pedro Gand\u00eda","@id":"https:\/\/www.pedro-gandia.com\/en\/#\/schema\/person\/d49ed006e171e8c59bc069054e7cda51"},"headline":"PARA\u00cdSO TERRENAL DE RICARDO LLOPESA","datePublished":"1996-07-20T16:37:08+00:00","dateModified":"2017-09-22T18:34:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/"},"wordCount":1595,"publisher":{"@id":"https:\/\/www.pedro-gandia.com\/en\/#\/schema\/person\/d49ed006e171e8c59bc069054e7cda51"},"articleSection":["Literature","Articles"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/","url":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/","name":"PARA\u00cdSO TERRENAL DE RICARDO LLOPESA - Pedro Gand\u00eda","isPartOf":{"@id":"https:\/\/www.pedro-gandia.com\/en\/#website"},"datePublished":"1996-07-20T16:37:08+00:00","dateModified":"2017-09-22T18:34:21+00:00","breadcrumb":{"@id":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pedro-gandia.com\/en\/paraiso-terrenal-de-ricardo-llopesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.pedro-gandia.com\/en\/"},{"@type":"ListItem","position":2,"name":"PARA\u00cdSO TERRENAL DE RICARDO LLOPESA"}]},{"@type":"WebSite","@id":"https:\/\/www.pedro-gandia.com\/en\/#website","url":"https:\/\/www.pedro-gandia.com\/en\/","name":"Pedro Gand\u00eda","description":"Art &amp; Literature","publisher":{"@id":"https:\/\/www.pedro-gandia.com\/en\/#\/schema\/person\/d49ed006e171e8c59bc069054e7cda51"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pedro-gandia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.pedro-gandia.com\/en\/#\/schema\/person\/d49ed006e171e8c59bc069054e7cda51","name":"Pedro Gand\u00eda","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g","caption":"Pedro Gand\u00eda"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/posts\/24164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/comments?post=24164"}],"version-history":[{"count":0,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/posts\/24164\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/media?parent=24164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/categories?post=24164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/tags?post=24164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}