{"id":24120,"date":"2017-08-04T19:21:00","date_gmt":"2017-08-04T17:21:00","guid":{"rendered":"https:\/\/www.pedro-gandia.com\/art\/videoarte\/"},"modified":"2017-10-08T18:08:37","modified_gmt":"2017-10-08T16:08:37","slug":"videoart","status":"publish","type":"page","link":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/","title":{"rendered":"Videoart"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; background_animation=&#8221;none&#8221; css_animation=&#8221;&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt; color: #808080;\">VIDEOART<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; background_animation=&#8221;none&#8221; css_animation=&#8221;&#8221;][vc_column][vc_empty_space height=&#8221;60px&#8221;]<div class='projects_holder_outer v4 portfolio_with_space portfolio_with_hover_text  qode-filter-position-top'>\n\t    \t<div class='projects_holder clearfix v4 hover_text portfolio_full_image '>\n\t\t<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"800\" height=\"800\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"Poema del Lago Hoa\u0300n Kie\u0302m\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem.jpg 800w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-700x700.jpg 700w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/poema-del-lago-hoan-kiem\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > POEMA DEL LAGO HO\u00c0N KI\u00caM<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/el-cementerio-marino-3\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > EL CEMENTERIO MARINO<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/intus\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > INTUS<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/untitled-2015-katrina-wolfe-butoh-dance\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > THE BODY SONG (2015) Katrina Wolfe butoh dance<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/narciso-o-el-plano-secuencia-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > NARCISO O EL PLANO SECUENCIA<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/el-mago\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > EL MAGO<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/viorel-en-el-jardin\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > VIOREL EN EL JARD\u00cdN<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t<\/div>\n\n    \n\t<\/div>\n[\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; background_animation=&#8221;none&#8221; css_animation=&#8221;&#8221;][vc_column offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][vc_column_text]Pedro Gand\u00eda Videoart. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school in Cuenca, a city that marked him by awakening in him, with its Museum of Abstract Art, a taste for art, to which his friendship with Fernando Z\u00f3bel contributed. Also for Literature, pleasure that he discovered through his teacher, and also friend, Vicente Tus\u00f3n. In 1972 he moved to Valencia and enrolled in the Superior Conservatory of Music and in the School of Arts and Crafts, disciplines that he later left for the studies of Philology. His literary education was marked by his stays in Paris and its museums between 1974 and 1976, as well as by his visits to Rome, Florence and London, where his pleasure in artistic creation was revived. He has been a painter (1982-1992), sculptor (1996-1999), professor of Literature, art dealer and director of the \u201cJade\u201d collections, of narrative and poetry, of the Institute of Modernist Studies. Since 2016, he has re-taken the brushes to paint, on some of his old canvases, his series \u201cEleg\u00edas\u201d.<\/p>\n<p>Pedro Gand\u00eda Videoart.\u00a0 If poetry was painting for Simonides of Ceos, and poetry was a talking image, it is fascinating to study the painted images (mute verses) of the poet-painter. The case is not uncommon; all knowledge tends by synthesis towards its visualization, and there are many \u00a0splendid examples throughout history: Salvador Rosa, Goethe, Garc\u00eda Lorca, William Blake, Moreno Villa \u2026<\/p>\n<p>Being the image, by definition, a set of forms and figures endowed with unity and signification, Pedro Gand\u00eda composes the images of his abstraction harmonizing forms and figures that could be said belonging to the color itself: each color seems to have its own body, skin and movement, as something inseparable from their pigmented reality.<\/p>\n<p>Pedro Gand\u00eda Videoart. The colors weigh, glide, embrace or become almost weightless waving its profile, as a sendal, to the impulse of an even lighter pigment; they interpret a slow dance, a movement always related to the musical that remembers \u201cstagings\u201d of settecentists\u2019 operas (perhaps Bibiena?); studies for a parsimonious and cyclopean choreography.<\/p>\n<p>The poet directs here the splendid music of Pedro Gand\u00eda\u2019s verses.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; background_animation=&#8221;none&#8221; css_animation=&#8221;&#8221;][vc_column][vc_column_text] VIDEOART [\/vc_column_text][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; background_animation=&#8221;none&#8221; css_animation=&#8221;&#8221;][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row][vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; background_animation=&#8221;none&#8221; css_animation=&#8221;&#8221;][vc_column offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][vc_column_text]Pedro Gand\u00eda Videoart. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he&#8230;<\/p>\n","protected":false},"author":1,"featured_media":25237,"parent":24095,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-24120","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pedro Gand\u00eda | Videoart<\/title>\n<meta name=\"description\" content=\"Pedro Gand\u00eda Videoart. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pedro Gand\u00eda | Videoart\" \/>\n<meta property=\"og:description\" content=\"Pedro Gand\u00eda Videoart. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedro Gand\u00eda\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-08T16:08:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Videoarte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@pedrogandia\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pedro Gand\u00eda | Videoart","description":"Pedro Gand\u00eda Videoart. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/","og_locale":"en_US","og_type":"article","og_title":"Pedro Gand\u00eda | Videoart","og_description":"Pedro Gand\u00eda Videoart. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school...","og_url":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/","og_site_name":"Pedro Gand\u00eda","article_modified_time":"2017-10-08T16:08:37+00:00","og_image":[{"width":1000,"height":272,"url":"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Videoarte.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@pedrogandia","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/","url":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/","name":"Pedro Gand\u00eda | Videoart","isPartOf":{"@id":"https:\/\/www.pedro-gandia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/#primaryimage"},"image":{"@id":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Videoarte.jpg","datePublished":"2017-08-04T17:21:00+00:00","dateModified":"2017-10-08T16:08:37+00:00","description":"Pedro Gand\u00eda Videoart. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school...","breadcrumb":{"@id":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/#primaryimage","url":"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Videoarte.jpg","contentUrl":"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Videoarte.jpg","width":1000,"height":272,"caption":"Pedro Gand\u00eda Videoart"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pedro-gandia.com\/en\/art\/videoart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.pedro-gandia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Art","item":"https:\/\/www.pedro-gandia.com\/en\/art\/"},{"@type":"ListItem","position":3,"name":"Videoart"}]},{"@type":"WebSite","@id":"https:\/\/www.pedro-gandia.com\/en\/#website","url":"https:\/\/www.pedro-gandia.com\/en\/","name":"Pedro Gand\u00eda","description":"Art &amp; Literature","publisher":{"@id":"https:\/\/www.pedro-gandia.com\/en\/#\/schema\/person\/d49ed006e171e8c59bc069054e7cda51"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pedro-gandia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.pedro-gandia.com\/en\/#\/schema\/person\/d49ed006e171e8c59bc069054e7cda51","name":"Pedro Gand\u00eda","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g","caption":"Pedro Gand\u00eda"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/pages\/24120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/comments?post=24120"}],"version-history":[{"count":0,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/pages\/24120\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/pages\/24095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/media\/25237"}],"wp:attachment":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/media?parent=24120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}