{"id":24095,"date":"2014-06-02T07:11:40","date_gmt":"2014-06-02T05:11:40","guid":{"rendered":"https:\/\/www.pedro-gandia.com\/arte\/"},"modified":"2017-10-08T14:58:56","modified_gmt":"2017-10-08T12:58:56","slug":"art","status":"publish","type":"page","link":"https:\/\/www.pedro-gandia.com\/en\/art\/","title":{"rendered":"Art"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; text_align=&#8221;center&#8221; background_animation=&#8221;none&#8221; padding_top=&#8221;40&#8243; padding_bottom=&#8221;90&#8243; css_animation=&#8221;&#8221;][vc_column]<div class='projects_holder_outer v4 portfolio_with_space portfolio_with_hover_text  qode-filter-position-top'>\n\t<div class='filter_outer center_align'>\n    <div class='filter_holder  without_separator'>\n        <ul>\n            \n                            <li class='filter' data-filter='all'><span>All<\/span><\/li>\n            \n                            <li class='filter' data-filter='portfolio_category_113'><span>SCULPTURE<\/span>\n                                <\/li>\n                            <li class='filter' data-filter='portfolio_category_114'><span>PHOTOGRAPHY<\/span>\n                                <\/li>\n                            <li class='filter' data-filter='portfolio_category_120'><span>PAINTING<\/span>\n                                <\/li>\n                            <li class='filter' data-filter='portfolio_category_125'><span>VIDEOART<\/span>\n                                <\/li>\n                    <\/ul>\n    <\/div>\n<\/div>\n    \t<div class='projects_holder clearfix v4 hover_text portfolio_full_image '>\n\t\t<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"800\" height=\"800\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"Poema del Lago Hoa\u0300n Kie\u0302m\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem.jpg 800w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Poema-del-Lago-Hoan-Kiem-700x700.jpg 700w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/poema-del-lago-hoan-kiem\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > POEMA DEL LAGO HO\u00c0N KI\u00caM<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/ELECTRIC-SWAN-3-cuadrado.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/ELECTRIC-SWAN-3-cuadrado.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/ELECTRIC-SWAN-3-cuadrado-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/ELECTRIC-SWAN-3-cuadrado-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/electric-swan-3\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Electric Swan 3<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"399\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Thong-destacada.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Thong-destacada.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Thong-destacada-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Thong-destacada-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/399;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/thong\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Thong<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Sol-y-sombra-Phrae-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Sol-y-sombra-Phrae-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Sol-y-sombra-Phrae-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Sol-y-sombra-Phrae-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sol-y-sombra\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Sol y sombra<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Deidades-Lampang-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Deidades-Lampang-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Deidades-Lampang-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Deidades-Lampang-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/deidades\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Deidades<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-wat-Prae-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-wat-Prae-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-wat-Prae-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-wat-Prae-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/en-el-wat\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > En el wat<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Acua\u0301tica-V-Phrae-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Acua\u0301tica-V-Phrae-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Acua\u0301tica-V-Phrae-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Acua\u0301tica-V-Phrae-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/acuatica-v\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Acu\u00e1tica V<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendario-Lampang-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendario-Lampang-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendario-Lampang-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendario-Lampang-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ofrendario-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Ofrendario<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/An\u0303o-nuevo-Lampang-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/An\u0303o-nuevo-Lampang-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/An\u0303o-nuevo-Lampang-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/An\u0303o-nuevo-Lampang-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ano-nuevo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > A\u00f1o nuevo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rosas-Lampang-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rosas-Lampang-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rosas-Lampang-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rosas-Lampang-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/rosas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Rosas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Floral-Bangkok-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Floral-Bangkok-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Floral-Bangkok-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Floral-Bangkok-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/floral\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Floral<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_118\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Travelo1-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Travelo1-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Travelo1-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Travelo1-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/travelo-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Travelo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PROJECTS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Floreros-Phrae-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Floreros-Phrae-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Floreros-Phrae-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Floreros-Phrae-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/floreros\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Floreros<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Consultando-el-mo\u0301vil-Lampang-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Consultando-el-mo\u0301vil-Lampang-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Consultando-el-mo\u0301vil-Lampang-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Consultando-el-mo\u0301vil-Lampang-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/consultando-el-movil\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Consultando el m\u00f3vil<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-azul-Bangkok-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-azul-Bangkok-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-azul-Bangkok-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-azul-Bangkok-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/florero-azul\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Florero azul<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rinco\u0301n-Napoli-2015-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rinco\u0301n-Napoli-2015-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rinco\u0301n-Napoli-2015-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rinco\u0301n-Napoli-2015-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/rincon-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Rinc\u00f3n<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Reflejo-Phrae-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Reflejo-Phrae-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Reflejo-Phrae-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Reflejo-Phrae-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/reflejo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Reflejo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Oferente-Phrae-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Oferente-Phrae-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Oferente-Phrae-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Oferente-Phrae-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/oferente\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Oferente<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Naturaleza-muerta-I-Beni-Mellal-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Naturaleza-muerta-I-Beni-Mellal-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Naturaleza-muerta-I-Beni-Mellal-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Naturaleza-muerta-I-Beni-Mellal-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/naturaleza-muerta-i\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Naturaleza muerta I<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Graffiti-Phrae-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Graffiti-Phrae-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Graffiti-Phrae-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Graffiti-Phrae-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/graffiti-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Graffiti<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_118\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Exo\u0301tica-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Exo\u0301tica-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Exo\u0301tica-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Exo\u0301tica-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/exotic\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Exotic<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PROJECTS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Tela-con-aran\u0303a-Phrae-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Tela-con-aran\u0303a-Phrae-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Tela-con-aran\u0303a-Phrae-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Tela-con-aran\u0303a-Phrae-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/tela-con-arana\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Tela con ara\u00f1a<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Taller-Beni-Mellal-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Taller-Beni-Mellal-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Taller-Beni-Mellal-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Taller-Beni-Mellal-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/taller\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Taller<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-Phrae-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-Phrae-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-Phrae-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-Phrae-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/flores-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flores<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-Phrae-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-Phrae-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-Phrae-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-Phrae-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/interior-4\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Interior<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-Phrae-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-Phrae-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-Phrae-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-Phrae-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/flor\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flor<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Wat-Phrae-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Wat-Phrae-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Wat-Phrae-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Wat-Phrae-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/wat\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Wat<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pagoda-Chiang-Mai-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pagoda-Chiang-Mai-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pagoda-Chiang-Mai-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pagoda-Chiang-Mai-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/pagoda\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Pagoda<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Antifaz-Fran-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Antifaz-Fran-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Antifaz-Fran-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Antifaz-Fran-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/antifaz\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Antifaz<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Aros-Lampang-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Aros-Lampang-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Aros-Lampang-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Aros-Lampang-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/aros-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Aros<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Chiang-Mai-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Chiang-Mai-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Chiang-Mai-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Chiang-Mai-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/bodegon-3\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bodeg\u00f3n<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Bangkok-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Bangkok-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Bangkok-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Bangkok-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/bodegon-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bodeg\u00f3n<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendario-Phrae-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendario-Phrae-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendario-Phrae-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendario-Phrae-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ofrendario\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Ofrendario<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_118\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Desnudos-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Desnudos-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Desnudos-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Desnudos-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/nudes\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Nudes<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PROJECTS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_118\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Androgynous400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Androgynous400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Androgynous400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Androgynous400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/androgynous-2-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Androgynous<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PROJECTS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-Bangkok-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-Bangkok-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-Bangkok-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-Bangkok-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/flores\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flores<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_118\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Vanitas-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Vanitas-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Vanitas-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Vanitas-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/vanitas-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Vanitas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PROJECTS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendas-Chiang-Mai-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendas-Chiang-Mai-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendas-Chiang-Mai-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ofrendas-Chiang-Mai-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ofrendas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Ofrendas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/An\u0303o-nuevo-Phrae-2017.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/An\u0303o-nuevo-Phrae-2017.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/An\u0303o-nuevo-Phrae-2017-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/An\u0303o-nuevo-Phrae-2017-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ano-nuevo-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > A\u00f1o nuevo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Telas-London-2016-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Telas-London-2016-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Telas-London-2016-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Telas-London-2016-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/telas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Telas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Al-cielo-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Al-cielo-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Al-cielo-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Al-cielo-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/al-cielo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Al cielo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Movimiento-London-2016-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Movimiento-London-2016-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Movimiento-London-2016-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Movimiento-London-2016-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/movimiento\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Movimiento<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Beni-Mellal-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Beni-Mellal-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Beni-Mellal-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Beni-Mellal-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/beni-mellal\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Beni Mellal<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Kiss-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Kiss-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Kiss-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Kiss-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/kiss\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Kiss<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/London-1016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/London-1016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/London-1016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/London-1016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/london\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > London<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_118\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Boys-Flowers-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Boys-Flowers-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Boys-Flowers-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Boys-Flowers-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/boys-flowers\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Boys &#038; Flowers<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PROJECTS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/City-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/City-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/City-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/City-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/city\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > City<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-con-cielo-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-con-cielo-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-con-cielo-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-con-cielo-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/flor-con-cielo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flor con cielo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ian-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ian-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ian-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ian-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ian\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Ian<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Zigzag-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Zigzag-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Zigzag-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Zigzag-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/zigzag\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Zigzag<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Space-Woman-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Space-Woman-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Space-Woman-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Space-Woman-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/space-woman\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Space Woman<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Abalorios-London-2016-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Abalorios-London-2016-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Abalorios-London-2016-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Abalorios-London-2016-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/abalorios\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Abalorios<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/bodegon-5\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bodeg\u00f3n<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Transparencias-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Transparencias-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Transparencias-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Transparencias-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/transparencias\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Transparencias<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colours-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colours-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colours-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colours-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/colours\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Colours<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bordados-veloces-London-2016-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bordados-veloces-London-2016-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bordados-veloces-London-2016-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bordados-veloces-London-2016-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/bordados-veloces\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bordados veloces<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-con-estatuas-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-con-estatuas-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-con-estatuas-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-con-estatuas-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/bodegon-con-estatuas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bodeg\u00f3n con estatuas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ramo-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ramo-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ramo-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ramo-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ramo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Ramo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-London-2016.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-London-2016.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-London-2016-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-London-2016-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/interior-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Interior<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ramaje-Napoli-2015.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ramaje-Napoli-2015.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ramaje-Napoli-2015-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ramaje-Napoli-2015-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ramaje\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Ramaje<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rinco\u0301n-Phrae-2017-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rinco\u0301n-Phrae-2017-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rinco\u0301n-Phrae-2017-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Rinco\u0301n-Phrae-2017-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/rincon\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Rinc\u00f3n<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Virgen-Napoli-2015-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Virgen-Napoli-2015-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Virgen-Napoli-2015-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Virgen-Napoli-2015-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/virgen\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Virgen<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Santi-sentado-Valencia-2015.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Santi-sentado-Valencia-2015.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Santi-sentado-Valencia-2015-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Santi-sentado-Valencia-2015-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/santi-sentado\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Santi sentado<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/A\u0301rbol-I-Napoli-2015.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/A\u0301rbol-I-Napoli-2015.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/A\u0301rbol-I-Napoli-2015-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/A\u0301rbol-I-Napoli-2015-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/arbol-i\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Arbol I<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Hue\u0301-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Hue\u0301-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Hue\u0301-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Hue\u0301-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/bodegon-4\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bodeg\u00f3n<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-muro-Berlin-2014-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-muro-Berlin-2014-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-muro-Berlin-2014-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-muro-Berlin-2014-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/en-el-muro\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > En el muro<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Nocturno-Hoi-An-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Nocturno-Hoi-An-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Nocturno-Hoi-An-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Nocturno-Hoi-An-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/nocturno\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Nocturno<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Hoi-An-Girl-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Hoi-An-Girl-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Hoi-An-Girl-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Hoi-An-Girl-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/hoi-an-girl\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Hoi An Girl<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Vanitas-Valencia-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Vanitas-Valencia-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Vanitas-Valencia-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Vanitas-Valencia-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/vanitas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Vanitas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Tu\u0308r-Berlin-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Tu\u0308r-Berlin-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Tu\u0308r-Berlin-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Tu\u0308r-Berlin-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/tur\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > T\u00fcr<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-Berlin-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-Berlin-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-Berlin-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Interior-Berlin-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/interior-3\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Interior<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Dang-Hue\u0301-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Dang-Hue\u0301-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Dang-Hue\u0301-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Dang-Hue\u0301-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/dang\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Dang<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Muro-I-Berli\u0301n-2014-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Muro-I-Berli\u0301n-2014-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Muro-I-Berli\u0301n-2014-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Muro-I-Berli\u0301n-2014-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/muro-i\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Muro I<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Daily-Smile-Berli\u0301n-2014-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Daily-Smile-Berli\u0301n-2014-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Daily-Smile-Berli\u0301n-2014-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Daily-Smile-Berli\u0301n-2014-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/daily-smile\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Daily smile<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Dogman-Berli\u0301n-2014-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Dogman-Berli\u0301n-2014-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Dogman-Berli\u0301n-2014-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Dogman-Berli\u0301n-2014-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/dogman\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Dogman<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Capilla-Hoi-An-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Capilla-Hoi-An-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Capilla-Hoi-An-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Capilla-Hoi-An-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/capilla\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Capilla<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Collage-en-muro-Berlin-2014-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Collage-en-muro-Berlin-2014-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Collage-en-muro-Berlin-2014-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Collage-en-muro-Berlin-2014-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/collage-en-muro\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Collage en muro<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Kue-Kue-Berli\u0301n-2014-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Kue-Kue-Berli\u0301n-2014-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Kue-Kue-Berli\u0301n-2014-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Kue-Kue-Berli\u0301n-2014-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/kue-kue\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Kue kue<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Graffiti-Hue\u0301-2014-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Graffiti-Hue\u0301-2014-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Graffiti-Hue\u0301-2014-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Graffiti-Hue\u0301-2014-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/graffiti\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Graffiti<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Apolo-Berli\u0301n-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Apolo-Berli\u0301n-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Apolo-Berli\u0301n-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Apolo-Berli\u0301n-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/apolo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Apolo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Aguacero-Hue\u0301-2014.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Aguacero-Hue\u0301-2014.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Aguacero-Hue\u0301-2014-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Aguacero-Hue\u0301-2014-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/aguacero-2-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Aguacero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/In-the-garden-London-2013.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/In-the-garden-London-2013.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/In-the-garden-London-2013-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/In-the-garden-London-2013-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/in-the-garden\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > In the garden<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-Valencia-2013.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-Valencia-2013.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-Valencia-2013-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-Valencia-2013-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/florero\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Florero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-cayendo-London-2013.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-cayendo-London-2013.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-cayendo-London-2013-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-cayendo-London-2013-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/flor-cayendo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flor cayendo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Despue\u0301s-del-aguacero-London-2013.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Despue\u0301s-del-aguacero-London-2013.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Despue\u0301s-del-aguacero-London-2013-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Despue\u0301s-del-aguacero-London-2013-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/despues-del-aguacero\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Despu\u00e9s del aguacero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-y-nubes-London-2013.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-y-nubes-London-2013.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-y-nubes-London-2013-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flor-y-nubes-London-2013-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/flor-y-nubes\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flor y nubes<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-London-2013.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-London-2013.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-London-2013-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Flores-London-2013-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/flores-3\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flores<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Composicio\u0301n-sobre-muro-London-2013-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Composicio\u0301n-sobre-muro-London-2013-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Composicio\u0301n-sobre-muro-London-2013-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Composicio\u0301n-sobre-muro-London-2013-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/composicion-sobre-muro\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Composici\u00f3n sobre muro<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Echinacea-y-cielo-London-2013.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Echinacea-y-cielo-London-2013.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Echinacea-y-cielo-London-2013-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Echinacea-y-cielo-London-2013-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/echinacea-y-cielo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Echinacea y cielo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Baco-negro-Moussa-2012.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Baco-negro-Moussa-2012.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Baco-negro-Moussa-2012-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Baco-negro-Moussa-2012-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/baco-negro\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Baco negro<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisajee-fluvial-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisajee-fluvial-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisajee-fluvial-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisajee-fluvial-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/paisaje-fluvial\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Paisaje fluvial<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Farola-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Farola-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Farola-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Farola-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/farola\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Farola<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Black-Swan-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Black-Swan-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Black-Swan-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Black-Swan-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/black-swan\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Black Swan<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lluvia-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lluvia-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lluvia-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lluvia-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/lluvia-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Lluvia<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Chandalero-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Chandalero-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Chandalero-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Chandalero-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/chandalero\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Chandalero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Adrien-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Adrien-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Adrien-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Adrien-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/adrien\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Adrien<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colgados-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colgados-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colgados-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colgados-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/colgados\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Colgados<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Red-flower-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Red-flower-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Red-flower-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Red-flower-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/red-flower\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Red flower<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Oton\u0303o-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Oton\u0303o-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Oton\u0303o-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Oton\u0303o-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/otono\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Oto\u00f1o<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Boxer-Moussa-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Boxer-Moussa-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Boxer-Moussa-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Boxer-Moussa-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/boxer\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Boxer<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisaje-interior-London-2011.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisaje-interior-London-2011.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisaje-interior-London-2011-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisaje-interior-London-2011-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/paisaje-interior\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Paisaje interior<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Conexio\u0301n-London-2010-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Conexio\u0301n-London-2010-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Conexio\u0301n-London-2010-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Conexio\u0301n-London-2010-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/conexion\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Conexi\u00f3n<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisaje-Rothko-Valencia-2010.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisaje-Rothko-Valencia-2010.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisaje-Rothko-Valencia-2010-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Paisaje-Rothko-Valencia-2010-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/paisaje-rothko\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Paisaje Rothko<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Inside-London-2010-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Inside-London-2010-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Inside-London-2010-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Inside-London-2010-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/inside\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Inside<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Cabezas-London-2010.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Cabezas-London-2010.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Cabezas-London-2010-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Cabezas-London-2010-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/cabezas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Cabezas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Marinero-Mario-2010.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Marinero-Mario-2010.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Marinero-Mario-2010-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Marinero-Mario-2010-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/marinero\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Marinero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ecuestre-Cairo-2009.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ecuestre-Cairo-2009.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ecuestre-Cairo-2009-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ecuestre-Cairo-2009-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ecuestre\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Ecuestre<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_116\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-muro-Safi-2009-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-muro-Safi-2009-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-muro-Safi-2009-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/En-el-muro-Safi-2009-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/en-el-muro-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > En el muro<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ COMPOSITIONS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-III-Valencia-2009.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-III-Valencia-2009.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-III-Valencia-2009-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Florero-III-Valencia-2009-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/florero-iii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Florero III<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Alejandri\u0301a-2009.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Alejandri\u0301a-2009.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Alejandri\u0301a-2009-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-Alejandri\u0301a-2009-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/bodegon\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bodeg\u00f3n<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_117\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Anciano-en-el-cafe\u0301-II.-Homenaje-a-Kavafis-Alejandri\u0301a-2009.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Anciano-en-el-cafe\u0301-II.-Homenaje-a-Kavafis-Alejandri\u0301a-2009.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Anciano-en-el-cafe\u0301-II.-Homenaje-a-Kavafis-Alejandri\u0301a-2009-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Anciano-en-el-cafe\u0301-II.-Homenaje-a-Kavafis-Alejandri\u0301a-2009-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/anciano-en-el-cafe-ii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Anciano en el caf\u00e9 II<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ LANDSCAPES    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-operario-Siwa-2009.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-operario-Siwa-2009.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-operario-Siwa-2009-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-operario-Siwa-2009-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/joven-operario\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Joven operario<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Johnny-con-uvas-Valencia-2009.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Johnny-con-uvas-Valencia-2009.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Johnny-con-uvas-Valencia-2009-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Johnny-con-uvas-Valencia-2009-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/johnny-con-uvas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Johnny con uvas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Couple-Tu\u0301nez-2008.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Couple-Tu\u0301nez-2008.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Couple-Tu\u0301nez-2008-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Couple-Tu\u0301nez-2008-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/couple\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Couple<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-colgante-Tozeur-2008.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-colgante-Tozeur-2008.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-colgante-Tozeur-2008-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bodego\u0301n-colgante-Tozeur-2008-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/bodegon-colgante\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bodeg\u00f3n colgante<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bozal-Valencia-2007.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bozal-Valencia-2007.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bozal-Valencia-2007-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Bozal-Valencia-2007-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/bozal\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bozal<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Entramado-Valencia-2007.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Entramado-Valencia-2007.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Entramado-Valencia-2007-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Entramado-Valencia-2007-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/entramado\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Entramado<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-Valencia-2005.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-Valencia-2005.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-Valencia-2005-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-Valencia-2005-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/viorel\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Viorel<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Mohamed-Tozeur-2004.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Mohamed-Tozeur-2004.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Mohamed-Tozeur-2004-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Mohamed-Tozeur-2004-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/mohamed\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Mohamed<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Amith-Luang-Prabang-2003.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Amith-Luang-Prabang-2003.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Amith-Luang-Prabang-2003-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Amith-Luang-Prabang-2003-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/amith\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Amith<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_115 portfolio_category_114\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Mesa-del-parai\u0301so-Dakar-2001.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Mesa-del-parai\u0301so-Dakar-2001.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Mesa-del-parai\u0301so-Dakar-2001-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Mesa-del-parai\u0301so-Dakar-2001-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/mesa-del-paraiso\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Mesa del para\u00edso<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSTILL-LIFES \/ PHOTOGRAPHY    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-egipcia-Aswan-2001.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-egipcia-Aswan-2001.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-egipcia-Aswan-2001-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-egipcia-Aswan-2001-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/joven-egipcia\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Joven egipcia<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Driss-Zagora-2001.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Driss-Zagora-2001.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Driss-Zagora-2001-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Driss-Zagora-2001-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/driss\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Driss<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colector-de-algas-Moulay-Abdelah-1998.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colector-de-algas-Moulay-Abdelah-1998.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colector-de-algas-Moulay-Abdelah-1998-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colector-de-algas-Moulay-Abdelah-1998-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/colector-de-algas-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Colector de algas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Larbi-Hausi\u0301a-1998.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Larbi-Hausi\u0301a-1998.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Larbi-Hausi\u0301a-1998-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Larbi-Hausi\u0301a-1998-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/larbi\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Larbi<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Nelcys-La-Habana-1995.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Nelcys-La-Habana-1995.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Nelcys-La-Habana-1995-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Nelcys-La-Habana-1995-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/nelcys\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Nelcys<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Chico-Pantera-Yovannis-1995.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Chico-Pantera-Yovannis-1995.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Chico-Pantera-Yovannis-1995-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Chico-Pantera-Yovannis-1995-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/chico-pantera\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Chico Pantera<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_114 portfolio_category_119\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colector-de-algas-Hausi\u0301a-1993.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colector-de-algas-Hausi\u0301a-1993.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colector-de-algas-Hausi\u0301a-1993-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Colector-de-algas-Hausi\u0301a-1993-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/colector-de-algas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Colector de algas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPHOTOGRAPHY \/ PORTRAITS    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-cementerio-marino-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/el-cementerio-marino-3\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > EL CEMENTERIO MARINO<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Ictus-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/intus\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > INTUS<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/butho-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/untitled-2015-katrina-wolfe-butoh-dance\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > THE BODY SONG (2015) Katrina Wolfe butoh dance<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Narciso-o-el-plano-secuencia-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/narciso-o-el-plano-secuencia-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > NARCISO O EL PLANO SECUENCIA<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/El-mago-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/el-mago\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > EL MAGO<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_125\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin.jpg 1080w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-300x300.jpg 300w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-768x768.jpg 768w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-1024x1024.jpg 1024w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-550x550.jpg 550w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-500x500.jpg 500w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-1000x1000.jpg 1000w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Viorel-en-el-jardin-700x700.jpg 700w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/viorel-en-el-jardin\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > VIOREL EN EL JARD\u00cdN<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tVIDEOART    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-COMPOSICIO\u0301N-II-1992-te\u0301mpera-sobre-carto\u0301n-14x12-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-COMPOSICIO\u0301N-II-1992-te\u0301mpera-sobre-carto\u0301n-14x12-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-COMPOSICIO\u0301N-II-1992-te\u0301mpera-sobre-carto\u0301n-14x12-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-COMPOSICIO\u0301N-II-1992-te\u0301mpera-sobre-carto\u0301n-14x12-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/composicion-ii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Composici\u00f3n II<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-A-Lucien-Letinois-1992-acri\u0301lico-s-lienzo-100x81-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-A-Lucien-Letinois-1992-acri\u0301lico-s-lienzo-100x81-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-A-Lucien-Letinois-1992-acri\u0301lico-s-lienzo-100x81-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-A-Lucien-Letinois-1992-acri\u0301lico-s-lienzo-100x81-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/a-lucien-letinois\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > A Lucien Letinois<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-AGUACERO-1991-acri\u0301lico-s-lienzo-61x74-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-AGUACERO-1991-acri\u0301lico-s-lienzo-61x74-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-AGUACERO-1991-acri\u0301lico-s-lienzo-61x74-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-AGUACERO-1991-acri\u0301lico-s-lienzo-61x74-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/aguacero\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Aguacero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-La\u0300-bas-1991-acri\u0301lico-s-lienzo-99x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-La\u0300-bas-1991-acri\u0301lico-s-lienzo-99x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-La\u0300-bas-1991-acri\u0301lico-s-lienzo-99x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-La\u0300-bas-1991-acri\u0301lico-s-lienzo-99x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/la-bas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > L\u00e0-bas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-Deesse-Immortelle-1991-acri\u0301lico-s-lienzo-61x38-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-Deesse-Immortelle-1991-acri\u0301lico-s-lienzo-61x38-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-Deesse-Immortelle-1991-acri\u0301lico-s-lienzo-61x38-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-Deesse-Immortelle-1991-acri\u0301lico-s-lienzo-61x38-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/deesse-immortelle\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Deesse Immortelle<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-CAIDA-1991-acri\u0301lico-s-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-CAIDA-1991-acri\u0301lico-s-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-CAIDA-1991-acri\u0301lico-s-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-CAIDA-1991-acri\u0301lico-s-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/caida\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Ca\u00edda<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-CAMPO-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-CAMPO-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-CAMPO-1991-acri\u0301lico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-CAMPO-1991-acri\u0301lico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/campo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Campo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-GRUTAS-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-GRUTAS-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-GRUTAS-1991-acri\u0301lico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-GRUTAS-1991-acri\u0301lico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/grutas\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Grutas<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-JARDI\u0301N-EN-OTON\u0303O-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-JARDI\u0301N-EN-OTON\u0303O-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-JARDI\u0301N-EN-OTON\u0303O-1991-acri\u0301lico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-JARDI\u0301N-EN-OTON\u0303O-1991-acri\u0301lico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/jardin-en-otono\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Jard\u00edn en oto\u00f1o<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-LA-CIUDAD-SELVA-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-LA-CIUDAD-SELVA-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-LA-CIUDAD-SELVA-1991-acri\u0301lico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-LA-CIUDAD-SELVA-1991-acri\u0301lico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/la-ciudad-selva\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > La ciudad-selva<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-LLUVIA-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-LLUVIA-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-LLUVIA-1991-acri\u0301lico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-LLUVIA-1991-acri\u0301lico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/lluvia\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Lluvia<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-OTRA-TARDE-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-OTRA-TARDE-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-OTRA-TARDE-1991-acri\u0301lico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-OTRA-TARDE-1991-acri\u0301lico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/la-otra-tarde\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > La otra tarde<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-SANGRE-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-SANGRE-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-SANGRE-1991-acri\u0301lico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-SANGRE-1991-acri\u0301lico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sangre\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Sangre<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-SECRETO-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-SECRETO-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-SECRETO-1991-acri\u0301lico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-SECRETO-1991-acri\u0301lico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/secreto\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Secreto<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/15-SIN-TI\u0301TULO-1991-acri\u0301lico-s-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/15-SIN-TI\u0301TULO-1991-acri\u0301lico-s-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/15-SIN-TI\u0301TULO-1991-acri\u0301lico-s-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/15-SIN-TI\u0301TULO-1991-acri\u0301lico-s-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/16-SIN-TI\u0301TULO-1991-acrilico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/16-SIN-TI\u0301TULO-1991-acrilico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/16-SIN-TI\u0301TULO-1991-acrilico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/16-SIN-TI\u0301TULO-1991-acrilico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-3\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/17-SIN-TI\u0301TULO-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/17-SIN-TI\u0301TULO-1991-acri\u0301lico-sobre-lienzo-33x41-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/17-SIN-TI\u0301TULO-1991-acri\u0301lico-sobre-lienzo-33x41-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/17-SIN-TI\u0301TULO-1991-acri\u0301lico-sobre-lienzo-33x41-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-4\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/18-PAISAJE-I-1991-acri\u0301lico-s-lienzo73x60-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/18-PAISAJE-I-1991-acri\u0301lico-s-lienzo73x60-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/18-PAISAJE-I-1991-acri\u0301lico-s-lienzo73x60-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/18-PAISAJE-I-1991-acri\u0301lico-s-lienzo73x60-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/paisaje-i\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Paisaje I<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/19-Serie-Alfabeto-H-1987-acri\u0301lico-s-cartulina-655x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/19-Serie-Alfabeto-H-1987-acri\u0301lico-s-cartulina-655x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/19-Serie-Alfabeto-H-1987-acri\u0301lico-s-cartulina-655x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/19-Serie-Alfabeto-H-1987-acri\u0301lico-s-cartulina-655x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/serie-alfabeto-h\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Serie Alfabeto, H<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/20-Serie-Alfabeto-A-1987-acri\u0301lico-s-carto\u0301n-297x21-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/20-Serie-Alfabeto-A-1987-acri\u0301lico-s-carto\u0301n-297x21-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/20-Serie-Alfabeto-A-1987-acri\u0301lico-s-carto\u0301n-297x21-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/20-Serie-Alfabeto-A-1987-acri\u0301lico-s-carto\u0301n-297x21-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/serie-alfabeto-a\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Serie Alfabeto, A<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/21-sin-ti\u0301tulo-1987-acri\u0301lico-s-cartulina-296x21-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/21-sin-ti\u0301tulo-1987-acri\u0301lico-s-cartulina-296x21-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/21-sin-ti\u0301tulo-1987-acri\u0301lico-s-cartulina-296x21-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/21-sin-ti\u0301tulo-1987-acri\u0301lico-s-cartulina-296x21-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-5\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/22-sin-ti\u0301tulo-1987-acri\u0301lico-s-cartulina-295x21-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/22-sin-ti\u0301tulo-1987-acri\u0301lico-s-cartulina-295x21-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/22-sin-ti\u0301tulo-1987-acri\u0301lico-s-cartulina-295x21-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/22-sin-ti\u0301tulo-1987-acri\u0301lico-s-cartulina-295x21-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-6\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/23-sin-ti\u0301tulo-1985-mixta-s-carto\u0301n-32x23-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/23-sin-ti\u0301tulo-1985-mixta-s-carto\u0301n-32x23-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/23-sin-ti\u0301tulo-1985-mixta-s-carto\u0301n-32x23-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/23-sin-ti\u0301tulo-1985-mixta-s-carto\u0301n-32x23-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-7\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/24-DI\u0301PTICO-X-1985-o\u0301leo-s-papel-2-hojas-de-30x21-copia.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/24-DI\u0301PTICO-X-1985-o\u0301leo-s-papel-2-hojas-de-30x21-copia.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/24-DI\u0301PTICO-X-1985-o\u0301leo-s-papel-2-hojas-de-30x21-copia-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/24-DI\u0301PTICO-X-1985-o\u0301leo-s-papel-2-hojas-de-30x21-copia-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/diptico-x\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > D\u00edptico X<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/25-SIN-TI\u0301TULO-1984-collage-mixto-te\u0301mpera-y-cera-50x355-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/25-SIN-TI\u0301TULO-1984-collage-mixto-te\u0301mpera-y-cera-50x355-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/25-SIN-TI\u0301TULO-1984-collage-mixto-te\u0301mpera-y-cera-50x355-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/25-SIN-TI\u0301TULO-1984-collage-mixto-te\u0301mpera-y-cera-50x355-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-8\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/sin-ti\u0301tulo-1984-o\u0301leo-sobre-lienzo-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/sin-ti\u0301tulo-1984-o\u0301leo-sobre-lienzo-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/sin-ti\u0301tulo-1984-o\u0301leo-sobre-lienzo-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/sin-ti\u0301tulo-1984-o\u0301leo-sobre-lienzo-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-31\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/26-SIN-TI\u0301TULO-1983-te\u0301mpera-s-cartulina-395x30-copia.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/26-SIN-TI\u0301TULO-1983-te\u0301mpera-s-cartulina-395x30-copia.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/26-SIN-TI\u0301TULO-1983-te\u0301mpera-s-cartulina-395x30-copia-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/26-SIN-TI\u0301TULO-1983-te\u0301mpera-s-cartulina-395x30-copia-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-9\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/sin-ti\u0301tulo-1983-o\u0301leo-sobre-lienzo-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/sin-ti\u0301tulo-1983-o\u0301leo-sobre-lienzo-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/sin-ti\u0301tulo-1983-o\u0301leo-sobre-lienzo-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/sin-ti\u0301tulo-1983-o\u0301leo-sobre-lienzo-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-30\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/27-SIN-TI\u0301TULO-1982-cera-s-carlulina-rosa-33x427-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/27-SIN-TI\u0301TULO-1982-cera-s-carlulina-rosa-33x427-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/27-SIN-TI\u0301TULO-1982-cera-s-carlulina-rosa-33x427-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/27-SIN-TI\u0301TULO-1982-cera-s-carlulina-rosa-33x427-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-10\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/28-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-naranja-328x426-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/28-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-naranja-328x426-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/28-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-naranja-328x426-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/28-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-naranja-328x426-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-11\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/29-SIN-TI\u0301TULO-1982-CERA-SOBRE-CARTULINA-NEGRA-425X323-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/29-SIN-TI\u0301TULO-1982-CERA-SOBRE-CARTULINA-NEGRA-425X323-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/29-SIN-TI\u0301TULO-1982-CERA-SOBRE-CARTULINA-NEGRA-425X323-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/29-SIN-TI\u0301TULO-1982-CERA-SOBRE-CARTULINA-NEGRA-425X323-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-12\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/30-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-roja325x428-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/30-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-roja325x428-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/30-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-roja325x428-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/30-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-roja325x428-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-13\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/31-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-verde-326x425-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/31-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-verde-326x425-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/31-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-verde-326x425-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/31-SIN-TI\u0301TULO-1982-cera-sobre-cartulina-verde-326x425-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-14\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/32-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-425x332-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/32-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-425x332-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/32-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-425x332-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/32-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-425x332-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-15\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/33-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-325x426-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/33-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-325x426-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/33-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-325x426-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/33-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-325x426-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-16\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/34-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-roja-426x325-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/34-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-roja-426x325-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/34-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-roja-426x325-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/34-SIN-TI\u0301TULO-1982-te\u0301mpera-s-cartulina-roja-426x325-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-17\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/35-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-azul-427x328-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/35-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-azul-427x328-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/35-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-azul-427x328-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/35-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-azul-427x328-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-18\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/36-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-651x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/36-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-651x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/36-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-651x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/36-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-651x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-19\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/37-sin-ti\u0301tulo-1982-acri\u0301lico-s-cartulina-65x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/37-sin-ti\u0301tulo-1982-acri\u0301lico-s-cartulina-65x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/37-sin-ti\u0301tulo-1982-acri\u0301lico-s-cartulina-65x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/37-sin-ti\u0301tulo-1982-acri\u0301lico-s-cartulina-65x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-20\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/38-Libro-de-Dzyan-Estancia-II-3-1982-acri\u0301lico-s-cartulina-65x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/38-Libro-de-Dzyan-Estancia-II-3-1982-acri\u0301lico-s-cartulina-65x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/38-Libro-de-Dzyan-Estancia-II-3-1982-acri\u0301lico-s-cartulina-65x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/38-Libro-de-Dzyan-Estancia-II-3-1982-acri\u0301lico-s-cartulina-65x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/libro-de-dzyan-estancia-ii-3-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Libro de Dzyan, Estancia II, 3<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/39-Libro-de-Dzyan-Estancia-II-2-1982-acri\u0301lico-s-cartulina-65x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/39-Libro-de-Dzyan-Estancia-II-2-1982-acri\u0301lico-s-cartulina-65x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/39-Libro-de-Dzyan-Estancia-II-2-1982-acri\u0301lico-s-cartulina-65x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/39-Libro-de-Dzyan-Estancia-II-2-1982-acri\u0301lico-s-cartulina-65x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/libro-de-dzyan-estancia-ii-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Libro de Dzyan, Estancia II, 2<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/40-A\u0301NGELES-1982-te\u0301mpera-s-cartulina-65x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/40-A\u0301NGELES-1982-te\u0301mpera-s-cartulina-65x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/40-A\u0301NGELES-1982-te\u0301mpera-s-cartulina-65x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/40-A\u0301NGELES-1982-te\u0301mpera-s-cartulina-65x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/angeles\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > \u00c1ngeles<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/41-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-negra-653x503-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/41-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-negra-653x503-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/41-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-negra-653x503-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/41-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-negra-653x503-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-21\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/42-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-65x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/42-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-65x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/42-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-65x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/42-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-65x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-22\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-DANZANTE-1993-te\u0301mpera-s-papel-serigrafiado-14x9-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-DANZANTE-1993-te\u0301mpera-s-papel-serigrafiado-14x9-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-DANZANTE-1993-te\u0301mpera-s-papel-serigrafiado-14x9-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-DANZANTE-1993-te\u0301mpera-s-papel-serigrafiado-14x9-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/danzante\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Danzante<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/43-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-653x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/43-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-653x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/43-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-653x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/43-SIN-TI\u0301TULO-1982-te\u0301mpera-sobre-cartulina-653x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-23\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lancero-I-1986-acri\u0301lico-sobre-lienzo-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lancero-I-1986-acri\u0301lico-sobre-lienzo-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lancero-I-1986-acri\u0301lico-sobre-lienzo-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lancero-I-1986-acri\u0301lico-sobre-lienzo-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/lancero-i\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Lancero I<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_121 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/44-PROMETEO-1982-te\u0301mpera-sobre-cartulina-854x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/44-PROMETEO-1982-te\u0301mpera-sobre-cartulina-854x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/44-PROMETEO-1982-te\u0301mpera-sobre-cartulina-854x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/44-PROMETEO-1982-te\u0301mpera-sobre-cartulina-854x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/prometeo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Prometeo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tABSTRACTIONS \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lancero-III-1986-acri\u0301lico-sobre-lienzo-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lancero-III-1986-acri\u0301lico-sobre-lienzo-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lancero-III-1986-acri\u0301lico-sobre-lienzo-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Lancero-III-1986-acri\u0301lico-sobre-lienzo-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/lancero-iii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Lancero III<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-LANCERO-1986-acri\u0301lico-s-lienzo-195x130-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-LANCERO-1986-acri\u0301lico-s-lienzo-195x130-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-LANCERO-1986-acri\u0301lico-s-lienzo-195x130-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-LANCERO-1986-acri\u0301lico-s-lienzo-195x130-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/lancero\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Lancero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-losanges-1986-acri\u0301lico-s-lienzo-97x130-coleccio\u0301n-del-artista-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-losanges-1986-acri\u0301lico-s-lienzo-97x130-coleccio\u0301n-del-artista-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-losanges-1986-acri\u0301lico-s-lienzo-97x130-coleccio\u0301n-del-artista-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-losanges-1986-acri\u0301lico-s-lienzo-97x130-coleccio\u0301n-del-artista-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/losanges\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Losanges<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-Sin-ti\u0301tulo-1986-acri\u0301lico-s-lienzo-96x130-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-Sin-ti\u0301tulo-1986-acri\u0301lico-s-lienzo-96x130-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-Sin-ti\u0301tulo-1986-acri\u0301lico-s-lienzo-96x130-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-Sin-ti\u0301tulo-1986-acri\u0301lico-s-lienzo-96x130-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-24\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-INTERIOR-1986-acri\u0301lico-sobre-lienzo-97x130-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-INTERIOR-1986-acri\u0301lico-sobre-lienzo-97x130-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-INTERIOR-1986-acri\u0301lico-sobre-lienzo-97x130-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-INTERIOR-1986-acri\u0301lico-sobre-lienzo-97x130-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/interior\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Interior<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-sin-ti\u0301tulo-1986-acri\u0301lico-s-lienzo-97x130-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-sin-ti\u0301tulo-1986-acri\u0301lico-s-lienzo-97x130-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-sin-ti\u0301tulo-1986-acri\u0301lico-s-lienzo-97x130-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-sin-ti\u0301tulo-1986-acri\u0301lico-s-lienzo-97x130-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-25\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-sin-ti\u0301tulo-1985-acri\u0301lico-s-lienzo-146x97-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-sin-ti\u0301tulo-1985-acri\u0301lico-s-lienzo-146x97-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-sin-ti\u0301tulo-1985-acri\u0301lico-s-lienzo-146x97-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-sin-ti\u0301tulo-1985-acri\u0301lico-s-lienzo-146x97-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-26\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-CA\u0301LIZ-Y-COLUMNA-1988-acri\u0301lico-s-carto\u0301n-36x29-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-CA\u0301LIZ-Y-COLUMNA-1988-acri\u0301lico-s-carto\u0301n-36x29-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-CA\u0301LIZ-Y-COLUMNA-1988-acri\u0301lico-s-carto\u0301n-36x29-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-CA\u0301LIZ-Y-COLUMNA-1988-acri\u0301lico-s-carto\u0301n-36x29-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/caliz-y-columna\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > C\u00e1liz y columna<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-CARLOS-1985-acri\u0301lico-s-lienzo-73x60-coleccio\u0301n-del-artista-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-CARLOS-1985-acri\u0301lico-s-lienzo-73x60-coleccio\u0301n-del-artista-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-CARLOS-1985-acri\u0301lico-s-lienzo-73x60-coleccio\u0301n-del-artista-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-CARLOS-1985-acri\u0301lico-s-lienzo-73x60-coleccio\u0301n-del-artista-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/carlos\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Carlos<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-palmeras-1987-acri\u0301lico-s-cartulina-295x21-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-palmeras-1987-acri\u0301lico-s-cartulina-295x21-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-palmeras-1987-acri\u0301lico-s-cartulina-295x21-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-palmeras-1987-acri\u0301lico-s-cartulina-295x21-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/palmeras\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Palmeras<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-arca\u0301ngel-1985-acri\u0301lico-s-lienzo-146x97-coleccio\u0301n-del-artista-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-arca\u0301ngel-1985-acri\u0301lico-s-lienzo-146x97-coleccio\u0301n-del-artista-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-arca\u0301ngel-1985-acri\u0301lico-s-lienzo-146x97-coleccio\u0301n-del-artista-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-arca\u0301ngel-1985-acri\u0301lico-s-lienzo-146x97-coleccio\u0301n-del-artista-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/arcangel\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Arc\u00e1ngel<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-RI\u0301O-ENTRE-PALMERAS-1987-acri\u0301lico-s-cartulina-50x70-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-RI\u0301O-ENTRE-PALMERAS-1987-acri\u0301lico-s-cartulina-50x70-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-RI\u0301O-ENTRE-PALMERAS-1987-acri\u0301lico-s-cartulina-50x70-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-RI\u0301O-ENTRE-PALMERAS-1987-acri\u0301lico-s-cartulina-50x70-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/rio-entre-palmeras\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > R\u00edo entre palmeras<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_122 portfolio_category_120\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-con-palmera-1985-acri\u0301lico-sobre-lienzo-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-con-palmera-1985-acri\u0301lico-sobre-lienzo-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-con-palmera-1985-acri\u0301lico-sobre-lienzo-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Joven-con-palmera-1985-acri\u0301lico-sobre-lienzo-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/joven-con-palmera\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Joven con palmera<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tFIGURE \/ PAINTING    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-PALMERAS-1987-acri\u0301lico-s-papel-295x21-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-PALMERAS-1987-acri\u0301lico-s-papel-295x21-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-PALMERAS-1987-acri\u0301lico-s-papel-295x21-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-PALMERAS-1987-acri\u0301lico-s-papel-295x21-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/palmeras-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Palmeras<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-LEVIATA\u0301N-1986-acri\u0301lico-s-carto\u0301n-27x27-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-LEVIATA\u0301N-1986-acri\u0301lico-s-carto\u0301n-27x27-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-LEVIATA\u0301N-1986-acri\u0301lico-s-carto\u0301n-27x27-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-LEVIATA\u0301N-1986-acri\u0301lico-s-carto\u0301n-27x27-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/leviatan\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Leviat\u00e1n<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-DESDE-EL-SUR-Reflejos-1-1986-te\u0301mpera-sobre-papel-30x21-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-DESDE-EL-SUR-Reflejos-1-1986-te\u0301mpera-sobre-papel-30x21-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-DESDE-EL-SUR-Reflejos-1-1986-te\u0301mpera-sobre-papel-30x21-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-DESDE-EL-SUR-Reflejos-1-1986-te\u0301mpera-sobre-papel-30x21-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/desde-el-sur-reflejos-1\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Desde el sur, Reflejos 1<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-DESDE-EL-SUR-Reflejos-6-1986-te\u0301mpera-sobre-papel-30x21-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-DESDE-EL-SUR-Reflejos-6-1986-te\u0301mpera-sobre-papel-30x21-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-DESDE-EL-SUR-Reflejos-6-1986-te\u0301mpera-sobre-papel-30x21-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-DESDE-EL-SUR-Reflejos-6-1986-te\u0301mpera-sobre-papel-30x21-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/desde-el-sur-reflejos-6\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Desde el sur, Reflejos 6<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-DESDE-EL-SUR-Palmeras-junto-al-agua-1986-te\u0301mpera-s-papel-30x21-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-DESDE-EL-SUR-Palmeras-junto-al-agua-1986-te\u0301mpera-s-papel-30x21-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-DESDE-EL-SUR-Palmeras-junto-al-agua-1986-te\u0301mpera-s-papel-30x21-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-DESDE-EL-SUR-Palmeras-junto-al-agua-1986-te\u0301mpera-s-papel-30x21-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/desde-el-sur-palmeras-junto-al-agua\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Desde el sur, Palmeras junto al agua<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-DESDE-EL-SUR-Junto-al-estanque-2-1986-te\u0301mpera-s-papel-30x21-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-DESDE-EL-SUR-Junto-al-estanque-2-1986-te\u0301mpera-s-papel-30x21-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-DESDE-EL-SUR-Junto-al-estanque-2-1986-te\u0301mpera-s-papel-30x21-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-DESDE-EL-SUR-Junto-al-estanque-2-1986-te\u0301mpera-s-papel-30x21-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/desde-el-sur-junto-al-estanque-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Desde el sur, Junto al estanque 2<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-paisaje-1986-acri\u0301lico-s-tabla-505x35-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-paisaje-1986-acri\u0301lico-s-tabla-505x35-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-paisaje-1986-acri\u0301lico-s-tabla-505x35-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-paisaje-1986-acri\u0301lico-s-tabla-505x35-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/paisaje\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Paisaje<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"399\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-nocturno-con-palmeras-1986-acrilico-s-lienzo-130x97-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-nocturno-con-palmeras-1986-acrilico-s-lienzo-130x97-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-nocturno-con-palmeras-1986-acrilico-s-lienzo-130x97-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-nocturno-con-palmeras-1986-acrilico-s-lienzo-130x97-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/399;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/nocturno-con-palmeras\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Nocturno con palmeras<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-desde-el-sur-1986-acri\u0301lic-s-lienzo-130x97-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-desde-el-sur-1986-acri\u0301lic-s-lienzo-130x97-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-desde-el-sur-1986-acri\u0301lic-s-lienzo-130x97-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-desde-el-sur-1986-acri\u0301lic-s-lienzo-130x97-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/desde-el-sur\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Desde el sur<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_124\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-Desde-el-Sur-1986-acri\u0301lico-y-esmalte-s-lienzo73x60-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-Desde-el-Sur-1986-acri\u0301lico-y-esmalte-s-lienzo73x60-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-Desde-el-Sur-1986-acri\u0301lico-y-esmalte-s-lienzo73x60-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-Desde-el-Sur-1986-acri\u0301lico-y-esmalte-s-lienzo73x60-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/desde-el-sur-2\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Desde el sur<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ LANDSCAPE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-elegi\u0301a-I-2016-o\u0301leo-s-lienzo-100x70-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-elegi\u0301a-I-2016-o\u0301leo-s-lienzo-100x70-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-elegi\u0301a-I-2016-o\u0301leo-s-lienzo-100x70-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-elegi\u0301a-I-2016-o\u0301leo-s-lienzo-100x70-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-i\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda I<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-elegi\u0301a-II-2016-o\u0301leo-s-lienzo-65x50-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-elegi\u0301a-II-2016-o\u0301leo-s-lienzo-65x50-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-elegi\u0301a-II-2016-o\u0301leo-s-lienzo-65x50-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-elegi\u0301a-II-2016-o\u0301leo-s-lienzo-65x50-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-ii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda II<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-elegi\u0301a-III-2016-o\u0301leo-s-lienzo-100x81-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-elegi\u0301a-III-2016-o\u0301leo-s-lienzo-100x81-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-elegi\u0301a-III-2016-o\u0301leo-s-lienzo-100x81-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/3-elegi\u0301a-III-2016-o\u0301leo-s-lienzo-100x81-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-iii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda III<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-elegi\u0301a-IV-2016-oleo-sobre-lienzo-65x46-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-elegi\u0301a-IV-2016-oleo-sobre-lienzo-65x46-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-elegi\u0301a-IV-2016-oleo-sobre-lienzo-65x46-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/4-elegi\u0301a-IV-2016-oleo-sobre-lienzo-65x46-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-iv\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda IV<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-elegi\u0301a-V-2016-o\u0301leo-s-lienzo-100x81-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-elegi\u0301a-V-2016-o\u0301leo-s-lienzo-100x81-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-elegi\u0301a-V-2016-o\u0301leo-s-lienzo-100x81-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-elegi\u0301a-V-2016-o\u0301leo-s-lienzo-100x81-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-v\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda V<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-Elegi\u0301a-VI-2016-o\u0301leo-s-lienzo-107x8350-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-Elegi\u0301a-VI-2016-o\u0301leo-s-lienzo-107x8350-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-Elegi\u0301a-VI-2016-o\u0301leo-s-lienzo-107x8350-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-Elegi\u0301a-VI-2016-o\u0301leo-s-lienzo-107x8350-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-vi\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda VI<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-elegi\u0301a-VII-2016-o\u0301leo-s-lienzo-100x81-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-elegi\u0301a-VII-2016-o\u0301leo-s-lienzo-100x81-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-elegi\u0301a-VII-2016-o\u0301leo-s-lienzo-100x81-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-elegi\u0301a-VII-2016-o\u0301leo-s-lienzo-100x81-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-vii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda VII<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-elegi\u0301a-VIII-2016-o\u0301leo-s-lienzo-130x89-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-elegi\u0301a-VIII-2016-o\u0301leo-s-lienzo-130x89-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-elegi\u0301a-VIII-2016-o\u0301leo-s-lienzo-130x89-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/8-elegi\u0301a-VIII-2016-o\u0301leo-s-lienzo-130x89-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-viii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda VIII<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-elegi\u0301a-IX-2016-61x38-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-elegi\u0301a-IX-2016-61x38-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-elegi\u0301a-IX-2016-61x38-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-elegi\u0301a-IX-2016-61x38-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-ix\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda IX<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-elegi\u0301a-X-2016-o\u0301leo-s-lienzo-100x81-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-elegi\u0301a-X-2016-o\u0301leo-s-lienzo-100x81-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-elegi\u0301a-X-2016-o\u0301leo-s-lienzo-100x81-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-elegi\u0301a-X-2016-o\u0301leo-s-lienzo-100x81-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/elegia-x\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Eleg\u00eda X<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-presagio-2016-o\u0301leo-s-lienzo-130x89-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-presagio-2016-o\u0301leo-s-lienzo-130x89-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-presagio-2016-o\u0301leo-s-lienzo-130x89-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/11-presagio-2016-o\u0301leo-s-lienzo-130x89-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/presagio\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Presagio<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-61x38-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-61x38-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-61x38-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-61x38-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-27\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-100x81-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-100x81-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-100x81-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-100x81-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-28\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_120 portfolio_category_123\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-146x97-1.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-146x97-1.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-146x97-1-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-sin-ti\u0301tulo-2016-o\u0301leo-s-lienzo-146x97-1-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo-29\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tPAINTING \/ RECENT WORK    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-TOTEM-IV.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-TOTEM-IV.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-TOTEM-IV-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/1-TOTEM-IV-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/totem-iv\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > T\u00f3tem IV<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-TOTEM-III.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-TOTEM-III.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-TOTEM-III-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/2-TOTEM-III-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/totem-iii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > T\u00f3tem III<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/TOTEM-II-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/TOTEM-II-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/TOTEM-II-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/TOTEM-II-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/totem-ii\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > T\u00f3tem II<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/TOTEM-I-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/TOTEM-I-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/TOTEM-I-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/TOTEM-I-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/totem-i\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > T\u00f3tem I<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-PALMERA-MUERTA.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-PALMERA-MUERTA.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-PALMERA-MUERTA-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/5-PALMERA-MUERTA-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/palmera-muerta\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Palmera muerta<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-DIABLO.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-DIABLO.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-DIABLO-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/6-DIABLO-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/diablo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Diablo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-ESPI\u0301RITU-DE-GUERRERO.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-ESPI\u0301RITU-DE-GUERRERO.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-ESPI\u0301RITU-DE-GUERRERO-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/7-ESPI\u0301RITU-DE-GUERRERO-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/espiritu-de-guerrero\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Esp\u00edritu de guerrero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/PRI\u0301NCIPE-GUERRERO-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/PRI\u0301NCIPE-GUERRERO-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/PRI\u0301NCIPE-GUERRERO-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/PRI\u0301NCIPE-GUERRERO-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/principe-guerrero\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Pr\u00edncipe guerrero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-GUERRERO.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-GUERRERO.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-GUERRERO-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/9-GUERRERO-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/guerrero\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Guerrero<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-HERMES.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-HERMES.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-HERMES-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/10-HERMES-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/hermes\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Hermes<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/ESCALA-400x400.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/ESCALA-400x400.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/ESCALA-400x400-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/ESCALA-400x400-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/escala\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Escala<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-YIN-YANG.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-YIN-YANG.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-YIN-YANG-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/12-YIN-YANG-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/ying-yang\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Ying &#8211; yang<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-ANTENA.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-ANTENA.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-ANTENA-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/13-ANTENA-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/antena\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Antena<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-SIN-TI\u0301TULO.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-SIN-TI\u0301TULO.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-SIN-TI\u0301TULO-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/14-SIN-TI\u0301TULO-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sin-titulo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > S\/T<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/15-SAGITARIO.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/15-SAGITARIO.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/15-SAGITARIO-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/15-SAGITARIO-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/sagitario\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Sagitario<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/16-EL-A\u0301RBOL-DEL-JARDI\u0301N.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/16-EL-A\u0301RBOL-DEL-JARDI\u0301N.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/16-EL-A\u0301RBOL-DEL-JARDI\u0301N-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/16-EL-A\u0301RBOL-DEL-JARDI\u0301N-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/el-arbol-del-jardin\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > El \u00e1rbol del jard\u00edn<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/17-VERDE-LUNA.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/17-VERDE-LUNA.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/17-VERDE-LUNA-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/17-VERDE-LUNA-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/verde-luna\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Verde luna<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/18-PA\u0301JARO-Y-POZO.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/18-PA\u0301JARO-Y-POZO.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/18-PA\u0301JARO-Y-POZO-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/18-PA\u0301JARO-Y-POZO-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/pajaro-y-pozo\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > P\u00e1jaro y pozo<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_113\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img decoding=\"async\" width=\"400\" height=\"400\" data-src=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/19-A\u0301RBOL.jpg\" class=\"attachment-full size-full wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/19-A\u0301RBOL.jpg 400w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/19-A\u0301RBOL-150x150.jpg 150w, https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/19-A\u0301RBOL-300x300.jpg 300w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.pedro-gandia.com\/en\/portfolio_page\/arbol\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > \u00c1rbol<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t<span class=\"project_category\">\n        <span> In <\/span>\n\t\tSCULPTURE    <\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t<\/div>\n\n    \n\t<\/div>\n[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; text_align=&#8221;center&#8221; background_animation=&#8221;none&#8221; padding_top=&#8221;40&#8243; padding_bottom=&#8221;90&#8243; css_animation=&#8221;&#8221;][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":25235,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-24095","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pedro Gand\u00eda | Art<\/title>\n<meta name=\"description\" content=\"Pedro Gand\u00eda Art. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school in...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pedro-gandia.com\/en\/art\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pedro Gand\u00eda | Art\" \/>\n<meta property=\"og:description\" content=\"Pedro Gand\u00eda Art. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school in...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pedro-gandia.com\/en\/art\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedro Gand\u00eda\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-08T12:58:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Arte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@pedrogandia\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pedro Gand\u00eda | Art","description":"Pedro Gand\u00eda Art. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school in...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pedro-gandia.com\/en\/art\/","og_locale":"en_US","og_type":"article","og_title":"Pedro Gand\u00eda | Art","og_description":"Pedro Gand\u00eda Art. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school in...","og_url":"https:\/\/www.pedro-gandia.com\/en\/art\/","og_site_name":"Pedro Gand\u00eda","article_modified_time":"2017-10-08T12:58:56+00:00","og_image":[{"width":1000,"height":272,"url":"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Arte.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@pedrogandia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pedro-gandia.com\/en\/art\/","url":"https:\/\/www.pedro-gandia.com\/en\/art\/","name":"Pedro Gand\u00eda | Art","isPartOf":{"@id":"https:\/\/www.pedro-gandia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pedro-gandia.com\/en\/art\/#primaryimage"},"image":{"@id":"https:\/\/www.pedro-gandia.com\/en\/art\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Arte.jpg","datePublished":"2014-06-02T05:11:40+00:00","dateModified":"2017-10-08T12:58:56+00:00","description":"Pedro Gand\u00eda Art. Was born on August 4, 1953, in Minglanilla, Cuenca, Spain, where he lived until he was nine years old. He studied secondary school in...","breadcrumb":{"@id":"https:\/\/www.pedro-gandia.com\/en\/art\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pedro-gandia.com\/en\/art\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pedro-gandia.com\/en\/art\/#primaryimage","url":"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Arte.jpg","contentUrl":"https:\/\/www.pedro-gandia.com\/wp-content\/uploads\/Pedro-Gandi\u0301a-Arte.jpg","width":1000,"height":272,"caption":"Pedro Gand\u00eda Art"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pedro-gandia.com\/en\/art\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.pedro-gandia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Art"}]},{"@type":"WebSite","@id":"https:\/\/www.pedro-gandia.com\/en\/#website","url":"https:\/\/www.pedro-gandia.com\/en\/","name":"Pedro Gand\u00eda","description":"Art &amp; Literature","publisher":{"@id":"https:\/\/www.pedro-gandia.com\/en\/#\/schema\/person\/d49ed006e171e8c59bc069054e7cda51"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pedro-gandia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.pedro-gandia.com\/en\/#\/schema\/person\/d49ed006e171e8c59bc069054e7cda51","name":"Pedro Gand\u00eda","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g","caption":"Pedro Gand\u00eda"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/46bb0d1adf0a5fcee6569ffb3fb75a79932bbcd104688fc95eb2e268b1276ae2?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/pages\/24095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/comments?post=24095"}],"version-history":[{"count":0,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/pages\/24095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/media\/25235"}],"wp:attachment":[{"href":"https:\/\/www.pedro-gandia.com\/en\/wp-json\/wp\/v2\/media?parent=24095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}